{"id":27214,"date":"2023-08-30T14:52:08","date_gmt":"2023-08-30T12:52:08","guid":{"rendered":"https:\/\/brandcompliance.com\/docs\/internal-audit\/"},"modified":"2026-09-01T14:36:28","modified_gmt":"2026-09-01T12:36:28","password":"","slug":"comment-realiser-un-audit-interne","status":"publish","type":"docs","link":"https:\/\/brandcompliance.com\/fr\/docs\/comment-realiser-un-audit-interne\/","title":{"rendered":"Comment r\u00e9aliser un audit interne"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignright wp-image-18751\" src=\"http:\/\/brandcompliance.com\/wp-content\/uploads\/2023\/07\/interne_audit-uitvoeren_web-300x200.jpg\" alt=\"comment r\u00e9aliser un audit interne\" width=\"381\" height=\"254\" srcset=\"https:\/\/brandcompliance.com\/wp-content\/uploads\/2023\/07\/interne_audit-uitvoeren_web-300x200.jpg 300w, https:\/\/brandcompliance.com\/wp-content\/uploads\/2023\/07\/interne_audit-uitvoeren_web-360x240.jpg 360w, https:\/\/brandcompliance.com\/wp-content\/uploads\/2023\/07\/interne_audit-uitvoeren_web.jpg 600w\" sizes=\"(max-width: 381px) 100vw, 381px\" \/>R\u00e9aliser des audits internes constitue une \u00e9tape importante pour maintenir et am\u00e9liorer un <a href=\"https:\/\/brandcompliance.com\/fr\/docs\/systeme-de-management\/\">syst\u00e8me de management<\/a>. Dans le cadre d\u2019un audit interne, votre organisation \u00e9value si les processus sont r\u00e9alis\u00e9s comme pr\u00e9vu et si le syst\u00e8me de management satisfait aux exigences de la norme applicable ainsi qu\u2019aux dispositions propres \u00e0 l\u2019organisation.<\/p>\n<p>Mais comment r\u00e9aliser un audit interne ? Quels \u00e9l\u00e9ments faut-il prendre en compte et quelles sont les \u00e9tapes importantes ? Dans cet article, nous expliquons comment pr\u00e9parer, r\u00e9aliser, documenter et assurer le suivi d\u2019un audit interne d\u2019un syst\u00e8me de management.<\/p>\n<h2>Que dit la norme ISO 19011 sur les audits internes ?<\/h2>\n<p>La <a href=\"https:\/\/www.iso.org\/fr\/standard\/19011\" target=\"_blank\" rel=\"noopener\">norme ISO 19011<\/a> fournit des lignes directrices pour l\u2019audit des syst\u00e8mes de management. Elle traite notamment des principes de l\u2019audit, de la gestion d\u2019un programme d\u2019audit, de la r\u00e9alisation des audits et de l\u2019\u00e9valuation des comp\u00e9tences des auditeurs.<\/p>\n<p>La norme ISO 19011 peut \u00eatre utilis\u00e9e comme support pratique lors de la planification et de la r\u00e9alisation des <a href=\"https:\/\/brandcompliance.com\/fr\/docs\/audit-interne-audit-externe\/\">audits internes<\/a>. Ces lignes directrices s\u2019appliquent aux organisations qui doivent r\u00e9aliser des audits internes de syst\u00e8mes de management ou g\u00e9rer un programme d\u2019audit.<\/p>\n<h2>Comment r\u00e9aliser un audit interne ?<\/h2>\n<p>Un audit interne n\u00e9cessite une approche structur\u00e9e. Cela permet \u00e0 votre organisation d\u2019\u00e9valuer si le syst\u00e8me de management fonctionne efficacement et si les processus satisfont aux exigences de la norme, aux politiques internes et aux proc\u00e9dures internes.<\/p>\n<p>Voici les principales \u00e9tapes de la r\u00e9alisation d\u2019un audit interne.<\/p>\n<h3>1. Pr\u00e9parer l&#8217;audit interne<\/h3>\n<p>Commencez par d\u00e9finir les objectifs de l\u2019audit, le champ de l\u2019audit et les crit\u00e8res d\u2019audit. D\u00e9terminez quelle partie du syst\u00e8me de management sera \u00e9valu\u00e9e, quels processus seront examin\u00e9s et quelles informations document\u00e9es ou exigences sont pertinentes. Planifiez ensuite les activit\u00e9s d\u2019audit et informez suffisamment \u00e0 l\u2019avance les employ\u00e9s concern\u00e9s. Une pr\u00e9paration ad\u00e9quate contribue \u00e0 la r\u00e9alisation efficace de l\u2019audit.<\/p>\n<h3>2. Examiner les informations document\u00e9es<\/h3>\n<p>Examinez au pr\u00e9alable les informations document\u00e9es pertinentes du syst\u00e8me de management. Celles-ci peuvent notamment comprendre les politiques, les proc\u00e9dures, les instructions de travail, les enregistrements, les objectifs, les indicateurs de performance et les r\u00e9sultats des audits pr\u00e9c\u00e9dents. Cette revue permet \u00e0 l\u2019auditeur interne de comprendre les processus et de r\u00e9aliser l\u2019audit de mani\u00e8re plus cibl\u00e9e.<\/p>\n<h3>3. R\u00e9aliser l&#8217;audit interne<\/h3>\n<p>Pendant l\u2019audit, l\u2019auditeur interne recueille des preuves d\u2019audit. Cela peut se faire au moyen d\u2019entretiens, de l\u2019examen des informations document\u00e9es, ainsi que par des observations au sein de l\u2019organisation. L\u2019auditeur \u00e9value si les processus sont r\u00e9alis\u00e9s conform\u00e9ment aux exigences et si le syst\u00e8me de management a \u00e9t\u00e9 mis en \u0153uvre efficacement. Les constats d\u2019audit doivent \u00eatre fond\u00e9s sur des preuves d\u2019audit objectives.<\/p>\n<h3>4. Analyser les constats d&#8217;audit<\/h3>\n<p>Une fois les activit\u00e9s d\u2019audit termin\u00e9es, l\u2019auditeur analyse les informations recueillies. Les constats d\u2019audit sont \u00e9valu\u00e9s au regard des crit\u00e8res d\u2019audit. Cela peut donner lieu \u00e0 des confirmations de conformit\u00e9, des points d\u2019attention, des possibilit\u00e9s d\u2019am\u00e9lioration ou des <a href=\"https:\/\/brandcompliance.com\/fr\/docs\/non-conformites-au-sein-du-systeme-de-management\/\">non-conformit\u00e9s<\/a>. Une non-conformit\u00e9 signifie qu\u2019une exigence de la norme, du syst\u00e8me de management ou des dispositions propres \u00e0 l\u2019organisation n\u2019a pas \u00e9t\u00e9 satisfaite.<\/p>\n<h3>5. Consigner les r\u00e9sultats de l&#8217;audit<\/h3>\n<p>Consignez les r\u00e9sultats de l\u2019audit interne dans un rapport d\u2019audit. Celui-ci doit notamment d\u00e9crire les objectifs de l\u2019audit, le champ de l\u2019audit, les crit\u00e8res d\u2019audit, la m\u00e9thode d\u2019audit, les constats d\u2019audit et les conclusions d\u2019audit. Communiquez le rapport aux parties int\u00e9ress\u00e9es pertinentes, y compris \u00e0 la direction. Les r\u00e9sultats des audits internes constituent \u00e9galement souvent une donn\u00e9e d\u2019entr\u00e9e pour la revue de direction.<\/p>\n<h3>6. Assurer le suivi des constats d&#8217;audit<\/h3>\n<p>Lorsque des non-conformit\u00e9s ou d\u2019autres probl\u00e8mes ont \u00e9t\u00e9 identifi\u00e9s, la direction d\u00e9termine les actions correctives n\u00e9cessaires. Il convient ensuite de v\u00e9rifier si ces actions ont \u00e9t\u00e9 mises en \u0153uvre et si elles sont efficaces. Le suivi des constats d\u2019audit issus des audits internes est important pour am\u00e9liorer le syst\u00e8me de management et pr\u00e9venir la r\u00e9currence des non-conformit\u00e9s.<\/p>\n<h2>L&#8217;audit interne comme pr\u00e9paration \u00e0 un audit de certification<\/h2>\n<p>Un audit interne constitue \u00e9galement une \u00e9tape importante dans la pr\u00e9paration \u00e0 un audit de certification. Lors d\u2019un audit de certification, un auditeur ind\u00e9pendant \u00e9value si le syst\u00e8me de management satisfait aux exigences de la norme.<\/p>\n<p>Votre <a href=\"https:\/\/brandcompliance.com\/fr\/docs\/audit-initial-etape-1\/\">premier audit de certification<\/a> approche ? Un audit interne correctement r\u00e9alis\u00e9 peut contribuer \u00e0 identifier \u00e0 l\u2019avance les \u00e9ventuels points d\u2019attention. Vous pouvez \u00e9galement consulter notre <a href=\"https:\/\/brandcompliance.com\/fr\/docs\/checklist-de-certification\/\">checklist de certification<\/a> pour conna\u00eetre les autres \u00e9tapes de pr\u00e9paration \u00e0 la certification.<\/p>\n<h2>R\u00e9aliser des audits internes de mani\u00e8re structur\u00e9e<\/h2>\n<p>La r\u00e9alisation d\u2019un audit interne n\u00e9cessite une pr\u00e9paration, une r\u00e9alisation, une documentation et un suivi rigoureux. En appliquant une approche structur\u00e9e, votre organisation acquiert une meilleure visibilit\u00e9 sur les performances de son syst\u00e8me de management et sur les possibilit\u00e9s d\u2019am\u00e9lioration.<\/p>\n<p>Consultez \u00e9galement les exigences relatives aux audits internes figurant dans la norme de syst\u00e8me de management applicable \u00e0 votre organisation. Dans de nombreuses normes de syst\u00e8mes de management, ces exigences sont reprises \u00e0 l\u2019article 9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9aliser des audits internes constitue une \u00e9tape importante pour maintenir et am\u00e9liorer un syst\u00e8me de management. Dans le cadre d\u2019un audit interne, votre organisation \u00e9value&#8230;<\/p>\n","protected":false},"author":22,"featured_media":27215,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"doc_category":[2392],"doc_tag":[],"class_list":["post-27214","docs","type-docs","status-publish","has-post-thumbnail","hentry","doc_category-preparation-certification"],"acf":[],"year_month":"2026-09","word_count":925,"total_views":"20","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Hilde","author_nicename":"hilde","author_url":"https:\/\/brandcompliance.com\/fr\/author\/hilde\/"},"doc_category_info":[{"term_name":"Pr\u00e9paration \u00e0 la certification","term_url":"https:\/\/brandcompliance.com\/fr\/docs-category\/preparation-certification\/"}],"doc_tag_info":[],"knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/brandcompliance.com\/fr\/wp-json\/wp\/v2\/docs\/27214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brandcompliance.com\/fr\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/brandcompliance.com\/fr\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/brandcompliance.com\/fr\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/brandcompliance.com\/fr\/wp-json\/wp\/v2\/comments?post=27214"}],"version-history":[{"count":4,"href":"https:\/\/brandcompliance.com\/fr\/wp-json\/wp\/v2\/docs\/27214\/revisions"}],"predecessor-version":[{"id":27220,"href":"https:\/\/brandcompliance.com\/fr\/wp-json\/wp\/v2\/docs\/27214\/revisions\/27220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brandcompliance.com\/fr\/wp-json\/wp\/v2\/media\/27215"}],"wp:attachment":[{"href":"https:\/\/brandcompliance.com\/fr\/wp-json\/wp\/v2\/media?parent=27214"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/brandcompliance.com\/fr\/wp-json\/wp\/v2\/doc_category?post=27214"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/brandcompliance.com\/fr\/wp-json\/wp\/v2\/doc_tag?post=27214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}